{"id":32113,"date":"2021-02-03T13:13:23","date_gmt":"2021-02-03T13:13:23","guid":{"rendered":"https:\/\/nicoschmit.lu\/klimaanlage\/"},"modified":"2026-06-10T14:57:13","modified_gmt":"2026-06-10T14:57:13","slug":"klimaanlage","status":"publish","type":"page","link":"https:\/\/nicoschmit.lu\/de\/klimaanlage\/","title":{"rendered":"Klimaanlage"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_code _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n            <div \n                class=\"elfsight-widget-slider elfsight-widget\" \n                data-elfsight-slider-options=\"%7B%22slides%22%3A%5B%7B%22media%22%3A%22https%3A%5C%2F%5C%2Fnicoschmit.lu%5C%2Fwp-content%5C%2Fuploads%5C%2F2021%5C%2F03%5C%2FiStock-1129543911-scaled-1.jpg%22%2C%22imageLink%22%3A%22%22%2C%22contentLayout%22%3A%22left%22%2C%22undefined%22%3Anull%2C%22contentTitleEnabled%22%3Afalse%2C%22contentTitleText%22%3A%22Sample%20Title%22%2C%22contentTitleColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22contentTitleFontSize%22%3A24%2C%22contentTitleFontWeight%22%3A%22normal%22%2C%22contentTextEnabled%22%3Afalse%2C%22contentTextText%22%3A%22%22%2C%22contentTextColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22contentTextFontSize%22%3A17%2C%22contentButtonEnabled%22%3Afalse%2C%22contentButtonText%22%3A%22Button%20Text%22%2C%22contentButtonLink%22%3A%22%22%2C%22contentButtonOpenLinkInNewTab%22%3Atrue%2C%22contentButtonColor%22%3A%22rgb%2828%2C%2035%2C%20255%29%22%2C%22contentButtonStyle%22%3A%22filled%22%2C%22contentButtonShape%22%3A4%2C%22contentButtonFontSize%22%3A16%2C%22contentMediaEnabled%22%3Afalse%2C%22contentMedia%22%3Anull%2C%22contentImageSize%22%3A100%2C%22contentBadgeEnabled%22%3Afalse%2C%22contentBadgeText%22%3A%22Sample%20Badge%22%2C%22contentBadgeColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22contentBadgeFontSize%22%3A13%2C%22contentBadgeStyle%22%3A%22filled%22%2C%22contentOverlayEnabled%22%3Afalse%2C%22contentOverlayColor%22%3A%22rgba%280%2C%200%2C%200%2C%20.5%29%22%2C%22contentHorizontalPosition%22%3A50%2C%22contentVerticalPosition%22%3A50%2C%22imageEffect%22%3A%22zoom%22%7D%5D%2C%22width%22%3A%22100%25%22%2C%22height%22%3A350%2C%22paginationEnabled%22%3Atrue%2C%22paginationStyle%22%3A%22bullets%22%2C%22paginationAlign%22%3A%22center%22%2C%22paginationPosition%22%3A%22inside%22%2C%22paginationColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22arrowsEnabled%22%3Atrue%2C%22arrowsPreviewNext%22%3Afalse%2C%22arrowsPosition%22%3A%22inside%22%2C%22arrowsColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22autoSlideEnabled%22%3Afalse%2C%22autoSlideDelay%22%3A5%2C%22autoSlidePauseOnHover%22%3Atrue%2C%22autoSlideProgressbar%22%3Atrue%2C%22transitionEffect%22%3A%22slide%22%2C%22transitionDuration%22%3A0.6%2C%22swipeEnabled%22%3Atrue%2C%22mobileSwipeEnabled%22%3Atrue%2C%22infiniteLoop%22%3Atrue%2C%22widgetId%22%3A%2215%22%7D\" \n                data-elfsight-slider-version=\"1.1.0\"\n                data-elfsight-widget-id=\"elfsight-slider-15\">\n            <\/div>\n            [\/et_pb_fullwidth_code][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#ffffff&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;80px||80px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; text_font=&#8220;||||||||&#8220; text_font_size=&#8220;35px&#8220; header_line_height=&#8220;1.6em&#8220; header_2_text_color=&#8220;#000000&#8243; header_2_line_height=&#8220;1.6em&#8220; header_3_line_height=&#8220;1.6em&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 class=\"page__title title\" id=\"page-title\" style=\"text-align: center;\">Klimaanlage<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;||||||||&#8220; text_text_color=&#8220;#000000&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p style=\"text-align: center;\">Virtueller Rundgang mit unserem Lieferanten Daikin. <a href=\"https:\/\/virtual-experience-center.daikin.eu\/#flipmouse\" target=\"_blank\" rel=\"noopener\">(Link)<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/nicoschmit.lu\/wp-content\/uploads\/2021\/03\/dk.png&#8220; title_text=&#8220;dk&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; text_font=&#8220;||||||||&#8220; text_text_color=&#8220;#000000&#8243; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Die meisten Menschen f\u00fchlen sich in einem Raumklima wohl, in dem die H\u00f6chsttemperatur 22 Grad Celsius und die Luftfeuchtigkeit 50 % betragen. Steigt die Temperatur weiter an oder nimmt die Luftfeuchtigkeit zu, empfinden wir das Raumklima als unangenehm, sind nicht mehr leistungsf\u00e4hig und k\u00f6nnen nachts schlecht schlafen. Von Entspannung kann also ebenfalls keine Rede sein. Die Investition in moderne Klimatechnik ist also eine Investition in das Wohlbefinden!   <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/nicoschmit.lu\/wp-content\/uploads\/\/2021\/03\/Wagner_Cooling-Systems.svg&#8220; title_text=&#8220;Wagner_Cooling-Systems&#8220; align=&#8220;right&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;50%&#8220; module_alignment=&#8220;right&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;https:\/\/nicoschmit.lu\/de\/&#8220; button_text=&#8220;Zur\u00fcck&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;16px&#8220; button_text_color=&#8220;#FFFFFF&#8220; button_bg_color=&#8220;#336fb5&#8243; button_border_width=&#8220;2px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\n            <div \n                class=\"elfsight-widget-slider elfsight-widget\" \n                data-elfsight-slider-options=\"%7B%22slides%22%3A%5B%7B%22media%22%3A%22https%3A%5C%2F%5C%2Fnicoschmit.lu%5C%2Fwp-content%5C%2Fuploads%5C%2F2021%5C%2F03%5C%2FiStock-1129543911-scaled-1.jpg%22%2C%22imageLink%22%3A%22%22%2C%22contentLayout%22%3A%22left%22%2C%22undefined%22%3Anull%2C%22contentTitleEnabled%22%3Afalse%2C%22contentTitleText%22%3A%22Sample%20Title%22%2C%22contentTitleColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22contentTitleFontSize%22%3A24%2C%22contentTitleFontWeight%22%3A%22normal%22%2C%22contentTextEnabled%22%3Afalse%2C%22contentTextText%22%3A%22%22%2C%22contentTextColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22contentTextFontSize%22%3A17%2C%22contentButtonEnabled%22%3Afalse%2C%22contentButtonText%22%3A%22Button%20Text%22%2C%22contentButtonLink%22%3A%22%22%2C%22contentButtonOpenLinkInNewTab%22%3Atrue%2C%22contentButtonColor%22%3A%22rgb%2828%2C%2035%2C%20255%29%22%2C%22contentButtonStyle%22%3A%22filled%22%2C%22contentButtonShape%22%3A4%2C%22contentButtonFontSize%22%3A16%2C%22contentMediaEnabled%22%3Afalse%2C%22contentMedia%22%3Anull%2C%22contentImageSize%22%3A100%2C%22contentBadgeEnabled%22%3Afalse%2C%22contentBadgeText%22%3A%22Sample%20Badge%22%2C%22contentBadgeColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22contentBadgeFontSize%22%3A13%2C%22contentBadgeStyle%22%3A%22filled%22%2C%22contentOverlayEnabled%22%3Afalse%2C%22contentOverlayColor%22%3A%22rgba%280%2C%200%2C%200%2C%20.5%29%22%2C%22contentHorizontalPosition%22%3A50%2C%22contentVerticalPosition%22%3A50%2C%22imageEffect%22%3A%22zoom%22%7D%5D%2C%22width%22%3A%22100%25%22%2C%22height%22%3A350%2C%22paginationEnabled%22%3Atrue%2C%22paginationStyle%22%3A%22bullets%22%2C%22paginationAlign%22%3A%22center%22%2C%22paginationPosition%22%3A%22inside%22%2C%22paginationColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22arrowsEnabled%22%3Atrue%2C%22arrowsPreviewNext%22%3Afalse%2C%22arrowsPosition%22%3A%22inside%22%2C%22arrowsColor%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22autoSlideEnabled%22%3Afalse%2C%22autoSlideDelay%22%3A5%2C%22autoSlidePauseOnHover%22%3Atrue%2C%22autoSlideProgressbar%22%3Atrue%2C%22transitionEffect%22%3A%22slide%22%2C%22transitionDuration%22%3A0.6%2C%22swipeEnabled%22%3Atrue%2C%22mobileSwipeEnabled%22%3Atrue%2C%22infiniteLoop%22%3Atrue%2C%22widgetId%22%3A%2215%22%7D\" \n                data-elfsight-slider-version=\"1.1.0\"\n                data-elfsight-widget-id=\"elfsight-slider-15\">\n            <\/div>\n            KlimaanlageVirtueller Rundgang mit unserem Lieferanten Daikin. (Link)Die meisten Menschen f\u00fchlen sich in einem Raumklima wohl, in dem die H\u00f6chsttemperatur 22 Grad Celsius und die Luftfeuchtigkeit 50 % betragen. Steigt die Temperatur weiter an oder nimmt die Luftfeuchtigkeit zu, empfinden wir das Raumklima als unangenehm, sind nicht mehr leistungsf\u00e4hig und k\u00f6nnen nachts schlecht schlafen. Von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-32113","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/pages\/32113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/comments?post=32113"}],"version-history":[{"count":11,"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/pages\/32113\/revisions"}],"predecessor-version":[{"id":32498,"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/pages\/32113\/revisions\/32498"}],"wp:attachment":[{"href":"https:\/\/nicoschmit.lu\/de\/wp-json\/wp\/v2\/media?parent=32113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}